{"id":3058,"date":"2023-03-28T12:37:08","date_gmt":"2023-03-28T10:37:08","guid":{"rendered":"https:\/\/www.gesundessalzburg.at\/amd\/?p=3058"},"modified":"2024-12-05T09:52:41","modified_gmt":"2024-12-05T08:52:41","slug":"wann-ist-ein-fahrrad-ein-arbeitsmittel","status":"publish","type":"post","link":"https:\/\/www.gesundessalzburg.at\/amd\/wann-ist-ein-fahrrad-ein-arbeitsmittel\/","title":{"rendered":"Wann ist ein Fahrrad <br>ein Arbeitsmittel?"},"content":{"rendered":"<p>\u201eAuch Fahrr\u00e4der k\u00f6nnen Arbeitsmittel sein\u201d, wei\u00df <a href=\"https:\/\/www.gesundessalzburg.at\/amd\/arbeitnehmerinnenschutz\/sicherheitstechnik\/\" target=\"_blank\" rel=\"noopener\">AMD-Salzburg-Sicherheitsfachkraft<\/a> <a href=\"https:\/\/www.gesundessalzburg.at\/amd\/ueber-uns\/team\/\" target=\"_blank\" rel=\"noopener\">Ing. Natascha Kojadinovic<\/a> und erg\u00e4nzt: \u201eDementsprechend m\u00fcssen auch die <strong>Drahtesel in einer Gef\u00e4hrdungsbeurteilung erfasst<\/strong> werden.\u201d Doch was bedeutet das nun f\u00fcr Salzburgs Betriebe?<\/p>\n<p>Im Endeffekt ist das recht einfach erkl\u00e4rt: Wenn ein Betrieb den Mitarbeiter*innen ein <strong>Dienstfahrrad<\/strong> zur Verf\u00fcgung stellt, <strong>muss<\/strong> auch ein entsprechender <strong>Arbeitsschutz garantiert werden<\/strong>. \u201eDazu geh\u00f6rt ein <strong>Fahrradcheck<\/strong>, der <strong>mindestens einmal pro Jahr<\/strong> von Fachpersonal durchgef\u00fchrt werden sollte\u201d, so Natascha Kojadinovic. Darin m\u00fcssen eine \u00dcberpr\u00fcfung der Verkehrssicherheit, Reparaturen und Wartungen \u2013 vor allem von Verschlei\u00dfteilen \u2013 enthalten sein. \u201eBei Fahrr\u00e4dern betrifft das h\u00e4ufig das Wechseln der Schl\u00e4uche, das Tauschen der Schaltz\u00fcge inklusive Einstellen der Schaltung und das Erneuern der Bremsbel\u00e4ge\u201d, erkl\u00e4rt die AMD-Salzburg-Technikerin.<\/p>\n<p>Dar\u00fcber hinaus sind <strong>Mitarbeiter*innen<\/strong> verpflichtet, sich selbst <strong>vor schweren Verletzungen zu sch\u00fctzen<\/strong>. Zur <strong>Minimalausr\u00fcstung<\/strong> geh\u00f6ren dabei ein <strong>Fahrradhelm<\/strong> und eine <strong>Warnweste<\/strong>. \u201eDer <strong>Helm<\/strong> sollte dabei <strong>alle drei bis f\u00fcnf Jahre ausgetauscht<\/strong> werden. Alle Mitarbeitenden, die ein Dienstfahrrad n\u00fctzen, sollten einen eigenen Helm bekommen\u201c, erkl\u00e4rt Natascha Kojadinovic. Beim <strong>Kauf eines Fahrradhelms<\/strong> sollte darauf geachtet werden, dass das Produkt nicht gebraucht ist, der <strong>Norm EN 1078<\/strong> entspricht und eine \u201e<strong>CE-Kennzeichnung<\/strong>\u201c aufweist. Die Helme sollten weder mit Aufklebern \u201eversch\u00f6nert\u201c noch direkt in der Sonne gelagert werden. Sowohl L\u00f6semittel in Klebstoffen als auch zu viel UV-Licht kann dem enthaltenen Kunststoff schaden. <strong>Warnwesten<\/strong> werden \u00fcber der Kleidung getragen und k\u00f6nnen somit <strong>von mehreren Mitarbeitenden<\/strong> genutzt werden. Zudem eignen sich Warnwesten dar\u00fcber hinaus auch hervorragend als gut sichtbare Werbefl\u00e4che.<\/p>\n<p>Mit diesen <strong>sieben Tipps<\/strong> sind Sie <strong>sicher im Stra\u00dfenverkehr<\/strong> unterwegs:<\/p>\n<ul>\n<li>Vor Fahrantritt <strong>Bremsen, Beleuchtung <\/strong>und <strong>Warneinrichtungen pr\u00fcfen<\/strong>.<\/li>\n<li>Es d\u00fcrfen mit einem Fahrrad <strong>keine schweren Lasten<\/strong> transportiert werden.<\/li>\n<li>Es ist <strong>geeignetes Schuhwerk<\/strong> (geschlossene, flache Schuhe) zu tragen.<\/li>\n<li>Zum Fahrradfahren sollten <strong>Helm und Warnweste<\/strong> selbstverst\u00e4ndlich dazugeh\u00f6ren.<\/li>\n<li>Die (Arbeits-)Abl\u00e4ufe sollten so organisiert werden, dass dadurch <strong>kein Zeitdruck im Stra\u00dfenverkehr <\/strong>entsteht.<\/li>\n<li>Vorhandene <strong>Radwege<\/strong> sollten <strong>unbedingt gen\u00fctzt <\/strong>werden.<strong><br \/>\n<\/strong><\/li>\n<li>Neben dem <strong>richtigen Verkehrsverhalten<\/strong> ist <strong>Aufmerksamkeit<\/strong> das oberste Gebot. Aus Sicherheitsgr\u00fcnden sollten w\u00e4hrend der Fahrt <strong>kein Handy<\/strong> und <strong>keine Kopfh\u00f6rer<\/strong> verwendet werden.<\/li>\n<\/ul>\n<p>Noch genauer sollten diese Tipps bei den immer beliebteren Elektrofahrr\u00e4dern beachtet werden: Mit <strong>E-Bikes<\/strong> lassen sich zwar auch <strong>l\u00e4ngere Strecken<\/strong> oder <strong>Strecken mit Steigungen bequem<\/strong> zur\u00fccklegen, allerdings ist man damit oft auch schneller unterwegs als beim Radfahren mit Muskelkraft. \u201eWichtig ist es auch hier, die <strong>Fahrgeschwindigkeit<\/strong> den Gegebenheiten und dem eigenen K\u00f6nnen <strong>anzupassen<\/strong>\u201c, r\u00e4t Natascha Kojadinovic.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eAuch Fahrr\u00e4der k\u00f6nnen Arbeitsmittel sein und m\u00fcssen in einer Gef\u00e4hrdungsbeurteilung erfasst werden.\u201d Doch was bedeutet das nun f\u00fcr Salzburgs Betriebe? Der AMD Salzburg hat die Antworten!<\/p>\n","protected":false},"author":2,"featured_media":3056,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amd-tipp"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/comments?post=3058"}],"version-history":[{"count":5,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3058\/revisions"}],"predecessor-version":[{"id":3108,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3058\/revisions\/3108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/media\/3056"}],"wp:attachment":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/media?parent=3058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/categories?post=3058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/tags?post=3058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}