{"id":3319,"date":"2023-08-16T16:02:22","date_gmt":"2023-08-16T14:02:22","guid":{"rendered":"https:\/\/www.gesundessalzburg.at\/amd\/?p=3319"},"modified":"2024-12-04T21:42:07","modified_gmt":"2024-12-04T20:42:07","slug":"bnw-seminar-gesundheitsziele-erreichen-mit-dem-zrm","status":"publish","type":"post","link":"https:\/\/www.gesundessalzburg.at\/amd\/bnw-seminar-gesundheitsziele-erreichen-mit-dem-zrm\/","title":{"rendered":"BNW-Seminar: &#8222;Gesundheitsziele <br>erreichen mit dem ZRM \u00ae&#8220;"},"content":{"rendered":"<p>Mit den Grundlagen des Z\u00fcricher Ressourcen Modells \u00ae (ZRM) besch\u00e4ftigt sich das Seminar von Kristina Sommerauer, MSc. Die Expertin in der Begleitung von Ver\u00e4nderungsprozessen und bed\u00fcrfnisorientierter Entwicklung nimmt sich hier einem wohlbekannten Ph\u00e4nomen an: Menschen, mit gesundheitlichen Problemen wissen dank professioneller Beratung sehr gut, welche Verhaltensver\u00e4nderungen zu einem gesundheitsorientierten Lebensstil beitragen k\u00f6nnen. Allerdings schaffen sie es nicht oder nicht ausreichend, entsprechende Gewohnheiten und Automatismen zu ver\u00e4ndern um alternative Gewohnheiten zum neuen Alltag zu machen. Im zweit\u00e4gigen Seminar lernen die Teilnehmer*innen wie Motivation entsteht und erleben, wie man Betroffenen die T\u00fcr zur inneren Motivation \u00f6ffnen kann, um eine Lebensstil\u00e4nderung generieren zu k\u00f6nnen.<\/p>\n<p>Das Seminar findet am Mittwoch, <strong>05. und 06. Oktober<\/strong> von <strong>09.00-17.00 Uhr<\/strong> ONLINE mittels Zoom statt. Die <strong>Anmeldung<\/strong> erfolgt direkt \u00fcber die <strong><a rel=\"nofollow\" target=\"_blank\"  href=\"https:\/\/weiterbildungsdatenbank.fgoe.org\/\">FG\u00d6-Weiterbildungsdatenbank<\/a><\/strong>. Die Teilnahmegeb\u00fchr betr\u00e4gt insgesamt 100 Euro.<\/p>\n<p>Hier k\u00f6nnen Sie die gesamte <a href=\"https:\/\/www.gesundessalzburg.at\/amd\/wp-content\/uploads\/2023\/04\/BNW-Programm-Salzburg-2023.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Bildungsnetzwerk-Brosch\u00fcre f\u00fcr Salzburg downloaden<\/strong>.<\/a><\/p>\n<p>&nbsp;<\/p>\n<h6>Unser &#8222;Social Media&#8220;:<\/h6>\n<p><a href=\"https:\/\/facebook.com\/avos.salzburg\/\" target=\"_blank\" rel=\"noopener\"><strong>Facebook:<\/strong> \u201eGesundes Salzburg: AVOS und AMD\u201c<\/a><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/gesundes_salzburg_avos_und_amd\/\" target=\"_blank\" rel=\"noopener\"><strong>Instagram:<\/strong> \u201eGesundes Salzburg: AVOS und AMD\u201c<\/a><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/company\/gesundessalzburg\/\" target=\"_blank\" rel=\"noopener\"><strong>LinkedIn:<\/strong> \u201eGesundes Salzburg: AVOS und AMD\u201c<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit den Grundlagen des Z\u00fcricher Ressourcen Modells \u00ae (ZRM) besch\u00e4ftigt sich das Seminar von Kristina Sommerauer, MSc, die sich einem wohlbekannten Ph\u00e4nomen annimmt.<\/p>\n","protected":false},"author":2,"featured_media":3320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amd-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/comments?post=3319"}],"version-history":[{"count":1,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3319\/revisions"}],"predecessor-version":[{"id":3321,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3319\/revisions\/3321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/media\/3320"}],"wp:attachment":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/media?parent=3319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/categories?post=3319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/tags?post=3319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}