{"id":3509,"date":"2024-05-28T12:31:47","date_gmt":"2024-05-28T10:31:47","guid":{"rendered":"https:\/\/www.gesundessalzburg.at\/amd\/?p=3509"},"modified":"2024-12-05T10:06:56","modified_gmt":"2024-12-05T09:06:56","slug":"so-gelingen-verstaendlicheunterweisungen-im-betrieb","status":"publish","type":"post","link":"https:\/\/www.gesundessalzburg.at\/amd\/so-gelingen-verstaendlicheunterweisungen-im-betrieb\/","title":{"rendered":"So gelingen verst\u00e4ndliche<br>Unterweisungen im Betrieb"},"content":{"rendered":"<p class=\"p1\">Als ein \u201e<b>Instrument f\u00fcr das Bewusstsein der Arbeitssicherheit im Unternehmen<\/b>\u201d bezeichnet AMD-Salzburg-Sicherheitsfachkraft Mag. Helga Lackinger die Unterweisung. Besonders wichtig dabei ist es, nicht nur stur auf die in \u00a714 des <b>Arbeitnehmer*innenschutzgesetzes (ASchG)<\/b>, <b>definierte Pflicht<\/b> zur regelm\u00e4\u00dfigen <b>Wiederholung wichtiger<\/b> und <b>sicherheitsrelevanter Themen<\/b> zu setzen, sondern auch dar\u00fcber hinaus davon zu profitieren. Und das kann gleich auf mehrere Arten geschehen, wie Mag. Helga Lackinger wei\u00df: \u201eNeben der Erf\u00fcllung der gesetzlichen Vorschriften k\u00f6nnen gut durchgef\u00fchrte Unterweisungen auch einen <b>reibungslosen Arbeitsablauf<\/b> garantieren und zum <b>Erfolg eines Betriebes<\/b> beitragen.\u201d<\/p>\n<p class=\"p2\">Dabei <b>m\u00fcssen Unterweisungen nach<a href=\"https:\/\/bit.ly\/3PRnN4Y\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" > \u00a714 des ASchG<\/a><\/b><br \/>\nimmer erfolgen,<\/p>\n<ul class=\"ul1\">\n<li class=\"li1\"><b>bevor eine T\u00e4tigkeit<\/b> zum ersten Mal aufgenommen wird.<\/li>\n<li class=\"li1\">wenn <b>jemand versetzt<\/b> wird oder sich <b>Aufgabenbereiche \u00e4ndern<\/b>.<\/li>\n<li class=\"li2\">wenn <b>neue Arbeitsmittel<\/b>,<b> Arbeitsstoffe<\/b> oder <b>Arbeitsverfahren<\/b> eingesetzt<br \/>\nwerden.<\/li>\n<li class=\"li2\">nachdem <b>Unf\u00e4lle<\/b> oder <b>Beinaheunf\u00e4lle<\/b> passiert sind.<\/li>\n<\/ul>\n<p class=\"p2\">Doch dar\u00fcber hinaus stellen Unterweisungen sowohl Arbeitgebende als auch Arbeitnehmende vor einige <b>Herausforderungen<\/b>, denn <b>\u201egeh\u00f6rt\u201d bedeutet nicht \u201everstanden\u201d<\/b>. \u201eEs geht nicht nur um das reine Weitergeben und Speichern von Wissen, sondern auch darum, dass die <b>Unterwiesenen verstehen<\/b>, worum es geht und dazu <b>motiviert werden<\/b>, sich an ihrem Arbeitsplatz sicher zu verhalten\u201d, so Mag. Helga Lackinger.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p2\">Sehr gut funktioniert das, wenn nicht jedes Jahr die gleichen Inhalte vermittelt, sondern <b>j\u00e4hrlich unterschiedliche Schwerpunkte<\/b> gesetzt werden \u2013 wie es der AMD Salzburg bei der <a href=\"https:\/\/www.stiegl.at\/\" target=\"_blank\" rel=\"noopener\"><b>Stieglbrauerei<\/b><\/a> umsetzt. \u201eDort funktioniert das sehr gut, die <b>Verantwortlichen zeigen sich offen<\/b> gegen\u00fcber<span class=\"Apple-converted-space\">\u00a0<\/span>neuen Methoden und auch die <b>Mitarbeitenden sind mit Eifer<\/b> dabei\u201d, freut sich Mag. Helga Lackinger. Im Teamwork erarbeiten hier die Stiegl-Angestellten gemeinsam mit der AMD-Salzburg-Sicherheitsfachkraft die geltenden Sicherheitsregeln anhand von Beispielfotos weitgehend selbst. \u201eDabei ist der Austausch wichtig und auch ein bisschen Humor hat nat\u00fcrlich Platz \u2013 es ist perfekt, wenn hier <b>Mitarbeitende als Expert*innen<\/b> in ihren Arbeitsbereichen gesehen werden und man dann <b>auf Augenh\u00f6he<\/b> erarbeitet, wie es eventuell noch besser funktionieren k\u00f6nnte.\u201d<\/p>\n<p class=\"p2\">Generell betrachtet der AMD Salzburg die <b>Unterweisungen als Unterst\u00fctzung f\u00fcr die Betriebe<\/b> und freut sich dar\u00fcber, hier auch <b>Vorzeigeunternehmen wie Stiegl <\/b>beratend <b>zur Seite zu stehen<\/b>.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p2\">Arbeitgebende haben ganz allgemein die Verpflichtung, Arbeitnehmende in allen Belangen zu informieren und zu unterweisen. Arbeitnehmende wiederum sind verpflichtet, diesen Unterweisungen und Anweisungen Folge zu leisten. Weitere Infos finden sich im <b>Merkblatt <a href=\"https:\/\/bit.ly\/3PX1CdD\" target=\"_blank\" rel=\"nofollow\" target=\"_blank\" >\u201eM070\u201d der AUVA<\/a>.<\/b><span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Besonders wichtig dabei ist, nicht nur auf die definierte Pflicht zu setzen, sondern auch daf\u00fcr zu sorgen, dass Mitarbeitende und Unternehmen von Unterweisungen profitieren.<\/p>\n","protected":false},"author":2,"featured_media":3506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amd-tipp"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/comments?post=3509"}],"version-history":[{"count":9,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3509\/revisions"}],"predecessor-version":[{"id":3519,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/posts\/3509\/revisions\/3519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/media\/3506"}],"wp:attachment":[{"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/media?parent=3509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/categories?post=3509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gesundessalzburg.at\/amd\/wp-json\/wp\/v2\/tags?post=3509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}